{"id":1697,"date":"2023-09-26T18:10:19","date_gmt":"2023-09-26T16:10:19","guid":{"rendered":"https:\/\/greenstarbau.hu\/?page_id=1697"},"modified":"2023-10-05T21:51:08","modified_gmt":"2023-10-05T19:51:08","slug":"referenciak","status":"publish","type":"page","link":"https:\/\/greenstarbau.hu\/en\/referenciak\/","title":{"rendered":"Referenci\u00e1k &#8211; GREEN STAR BAU"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1697\" class=\"elementor elementor-1697\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb43d88 e-flex e-con-boxed e-con e-parent\" data-id=\"bb43d88\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ed8372d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ed8372d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;bounceInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Two examples of \"Before-After\" work.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5cb043a e-grid e-con-boxed e-con e-parent\" data-id=\"5cb043a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fef1191 elementor-widget elementor-widget-elementskit-image-comparison\" data-id=\"fef1191\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-image-comparison.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-image-comparison image-comparison-container\" data-offset=\"0.5\" data-overlay=\"true\" data-label_after=\"UTNA\" data-label_before=\"ELTTE\" data-move_slider_on_hover=\"\" data-click_to_move=\"\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/ref_001.jpg\" title=\"ref_001\" alt=\"ref_001\" loading=\"lazy\" \/><img decoding=\"async\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/ref_002.jpg\" title=\"ref_002\" alt=\"ref_002\" loading=\"lazy\" \/>\t\t<\/div>\n\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3e6d21f elementor-widget elementor-widget-elementskit-image-comparison\" data-id=\"3e6d21f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-image-comparison.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" >\n\t\t<div class=\"elementskit-image-comparison image-comparison-container-vertical\" data-offset=\"0.5\" data-overlay=\"\" data-label_after=\"UTNA\" data-label_before=\"ELTTE\" data-move_slider_on_hover=\"\" data-click_to_move=\"\">\n\t\t\t<img decoding=\"async\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/10\/ref-222.jpg\" title=\"ref-222\" alt=\"ref-222\" loading=\"lazy\" \/><img decoding=\"async\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/10\/ref-223.jpg\" title=\"ref-223\" alt=\"ref-223\" loading=\"lazy\" \/>\t\t<\/div>\n\n\t<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-37493c8 e-flex e-con-boxed e-con e-parent\" data-id=\"37493c8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a17b016 elementor-widget elementor-widget-spacer\" data-id=\"a17b016\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c62e0e e-flex e-con-boxed e-con e-child\" data-id=\"9c62e0e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;shape_divider_bottom&quot;:&quot;tilt&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-shape elementor-shape-bottom\" aria-hidden=\"true\" data-negative=\"false\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewbox=\"0 0 1000 100\" preserveaspectratio=\"none\">\n\t<path class=\"elementor-shape-fill\" d=\"M0,6V0h1000v100L0,6z\"\/>\n<\/svg>\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f1071f7 e-grid e-con-boxed e-con e-child\" data-id=\"f1071f7\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-c82b986 e-grid e-con-boxed e-con e-child\" data-id=\"c82b986\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e21ace elementor-widget elementor-widget-elementskit-heading\" data-id=\"4e21ace\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"elementskit-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"ekit-wid-con\" ><div class=\"ekit-heading elementskit-section-title-wraper text_left   ekit_heading_tablet-   ekit_heading_mobile-\"><h2 class=\"ekit-heading--title elementskit-section-title\">Work photos<\/h2><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f7283d elementor-widget elementor-widget-text-editor\" data-id=\"6f7283d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>Real recordings from our everyday life.\u00a0<\/strong><\/p><p style=\"text-align: center;\">Perhaps these pictures also clearly show the precision, the choice of the right technology and machine park.<br \/>We work carefully, as if we were doing it only for ourselves.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-87224f4 elementor-arrows-position-inside elementor-widget elementor-widget-image-carousel\" data-id=\"87224f4\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;arrows&quot;,&quot;speed&quot;:1000,&quot;slides_to_show&quot;:&quot;3&quot;,&quot;slides_to_scroll&quot;:&quot;3&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"K\u00e9p k\u00f6rhinta\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper swiper-image-stretch\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380861131_275168222007618_2894857585304945250_n-1140x1710.jpg\" alt=\"380861131_275168222007618_2894857585304945250_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380861131_970534084206318_7302127969703654808_n-1140x1710.jpg\" alt=\"380861131_970534084206318_7302127969703654808_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380922345_6382573338537353_5830948455776384190_n-1140x1710.jpg\" alt=\"380922345_6382573338537353_5830948455776384190_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380925128_832920691711830_6341667855866736485_n-1140x1710.jpg\" alt=\"380925128_832920691711830_6341667855866736485_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380925128_880661960329679_606355084481474386_n-1140x1710.jpg\" alt=\"380925128_880661960329679_606355084481474386_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380927787_1479780999535713_2500437773976429001_n-1140x1710.jpg\" alt=\"380927787_1479780999535713_2500437773976429001_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380927796_1092521225046309_1409584995583282470_n-1140x1710.jpg\" alt=\"380927796_1092521225046309_1409584995583282470_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380927797_3510798075825593_6559247109768285084_n-1140x1710.jpg\" alt=\"380927797_3510798075825593_6559247109768285084_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380930672_659389789503884_6014122909570929085_n-1140x1710.jpg\" alt=\"380930672_659389789503884_6014122909570929085_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380933653_184621944654225_7109634026747781515_n-1140x1710.jpg\" alt=\"380933653_184621944654225_7109634026747781515_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380936676_587050043638716_641951716398778148_n-1140x1710.jpg\" alt=\"380936676_587050043638716_641951716398778148_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380940103_261500990193618_3138551889263902383_n-1140x1710.jpg\" alt=\"380940103_261500990193618_3138551889263902383_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380940109_1033618294320921_735586706722601315_n-1140x1710.jpg\" alt=\"380940109_1033618294320921_735586706722601315_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380959067_276807195290541_4927060109418259281_n-1140x1710.jpg\" alt=\"380959067_276807195290541_4927060109418259281_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380967281_306538035403570_1834007473404186580_n-1140x1710.jpg\" alt=\"380967281_306538035403570_1834007473404186580_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380971105_3207693389525352_7529654704372519103_n-1140x1710.jpg\" alt=\"380971105_3207693389525352_7529654704372519103_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380971106_329297799510798_6779118096167170197_n-1140x1710.jpg\" alt=\"380971106_329297799510798_6779118096167170197_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380979592_833020471652655_6623261230069247994_n-1140x1710.jpg\" alt=\"380979592_833020471652655_6623261230069247994_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/380992017_1032097834803273_188828634657047882_n-1140x1710.jpg\" alt=\"380992017_1032097834803273_188828634657047882_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/381000550_1313868309247654_6194354252451799230_n-1140x1710.jpg\" alt=\"381000550_1313868309247654_6194354252451799230_n\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 \/ 21\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/greenstarbau.hu\/wp-content\/uploads\/2023\/09\/381983440_346095731179179_493954859166188562_n-1140x1710.jpg\" alt=\"381983440_346095731179179_493954859166188562_n\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e54e501 elementor-widget elementor-widget-spacer\" data-id=\"e54e501\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b8b2a7 elementor-widget elementor-widget-spacer\" data-id=\"5b8b2a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>K\u00e9t p\u00e9lda &#8222;El\u0151tte-Ut\u00e1na&#8221; munk\u00e1ra. Munkak\u00e9pek Val\u00f3s felv\u00e9telek a h\u00e9tk\u00f6znapjainkb\u00f3l.\u00a0 Tal\u00e1n ezeken a k\u00e9peken is j\u00f3l l\u00e1that\u00f3 a precizit\u00e1s, a megfelel\u0151 technol\u00f3gia \u00e9s g\u00e9ppark v\u00e1laszt\u00e1sa.Ig\u00e9nyesen dolgozunk, mint ha csak magunknak tenn\u00e9nk.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1697","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/pages\/1697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/comments?post=1697"}],"version-history":[{"count":51,"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/pages\/1697\/revisions"}],"predecessor-version":[{"id":2131,"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/pages\/1697\/revisions\/2131"}],"wp:attachment":[{"href":"https:\/\/greenstarbau.hu\/en\/wp-json\/wp\/v2\/media?parent=1697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}